{"id":719,"date":"2016-03-21T16:28:21","date_gmt":"2016-03-21T19:28:21","guid":{"rendered":"http:\/\/tecnicos.org.ar\/colegio\/?p=719"},"modified":"2016-04-28T12:39:09","modified_gmt":"2016-04-28T15:39:09","slug":"gestionar-poliza-de-seguros","status":"publish","type":"post","link":"https:\/\/tecnicos.org.ar\/colegio\/gestionar-poliza-de-seguros\/","title":{"rendered":"Datos para gestionar su p\u00f3liza de seguros"},"content":{"rendered":"<p>Dando click aqu\u00ed o ingresando a la secci\u00f3n Sancor Seguros dentro de Beneficios, acceder\u00e1 a los datos para ponerse en contacto con Cristina Da Rold y poder solicitar su p\u00f3liza de seguros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dando click aqu\u00ed o ingresando a la secci\u00f3n Sancor Seguros dentro de Beneficios, acceder\u00e1 a los datos para ponerse en contacto con Cristina Da Rold y poder solicitar su p\u00f3liza &#8230;<\/p>\n","protected":false},"author":1,"featured_media":720,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":"","_elementor_edit_mode":"","_elementor_template_type":"","_elementor_data":"","_elementor_page_settings":null,"_elementor_conditions":[]},"categories":[7],"tags":[],"class_list":["post-719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/posts\/719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/comments?post=719"}],"version-history":[{"count":3,"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/posts\/719\/revisions"}],"predecessor-version":[{"id":797,"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/posts\/719\/revisions\/797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/media\/720"}],"wp:attachment":[{"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/media?parent=719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/categories?post=719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/tecnicos.org.ar\/colegio\/wp-json\/wp\/v2\/tags?post=719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}